{"id":853,"date":"2016-10-05T23:04:48","date_gmt":"2016-10-05T21:04:48","guid":{"rendered":"http:\/\/nachwuchs.ehc-klostersee.de\/schueler\/?p=853"},"modified":"2016-10-05T23:08:15","modified_gmt":"2016-10-05T21:08:15","slug":"02-10-2016-hc-landsberg-ehc-klostersee-46-14-10-22","status":"publish","type":"post","link":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/2016\/10\/05\/02-10-2016-hc-landsberg-ehc-klostersee-46-14-10-22\/","title":{"rendered":"02.10.2016 HC Landsberg &#8211; EHC Klostersee 4:6 (1:4; 1:0; 2:2)"},"content":{"rendered":"<p><strong>Sch\u00fclerteam weiter erfolgreich \u2013 EHC gewinnt 6:4 in Landsberg.\u00a0<\/strong><\/p>\n<p>Nach dem erfolgreichen Auftaktwochende wartete am Sonntagnachmittag mit dem HC Landsberg die n\u00e4chste Ausw\u00e4rtsh\u00fcrde auf die EHC-Sch\u00fcler.<\/p>\n<p>Wie bereits im ersten Spiel gegen Pei\u00dfenberg kamen die EHCler hellwach aus der Kabine und legten bereits in der 2. Minute vor: 1:0 durch Michael Reiter nach sch\u00f6ner Kombination \u00fcber Stefan W\u00fcrmseer und Tobias Langenbein.<\/p>\n<p>Nach dem etwas ungl\u00fccklichen Ausgleich in der 7. Minute ging es dann Schlag auf Schlag: Innerhalb von nur 44 Sekunden schraubten Ole Hofmann, Michael Reiter und Stefan W\u00fcrmseer das Ergebnis gegen kurzzeitig indisponierte Landsberger auf 4:1 in die H\u00f6he. Drei Tore innerhalb von 44 Sekunden sieht man auch im Eishockey nicht alle Tage. Es sollte aber nicht die einzige Merkw\u00fcrdigkeit an diesem Nachmittag gewesen sein.<\/p>\n<p>Im Anschluss hatten die EHC-Sch\u00fcler das Spiel sicher im Griff, erarbeiteten sich eine Vielzahl hochkar\u00e4tiger Chancen &#8211; und vergaben sie alle. Mit 4:1 und einem scheinbar komfortablen Vorsprung ging es in die Kabinen.<\/p>\n<p>Nur 35 Sekunden nach Wideranpfiff zum zweiten Drittel zappelte der Puck bereits im EHC-Netz, Landsberg hatte auf 2:4 verk\u00fcrzt und vorbei war es mit der \u00dcberlegenheit aus dem ersten Drittel. Der wieder sehr gut haltende Goalie Carsten Aurich hatte alle H\u00e4nde voll zu tun um Schlimmeres zu verhindern.<\/p>\n<p>Im letzten Drittel kam es, wie es kommen musste: Es dauerte nur knapp 2 Minuten bis die durch 3 Spieler von Bundesligist Augsburg verst\u00e4rkten Riverkings zum Ausgleich kamen. Allerdings h\u00e4tte das vierte Landsberger Tor nicht z\u00e4hlen d\u00fcrfen. Vom Pfosten sprang der Puck an die Kufe des EHC-Goalies und von dort in&#8217;s Feld zur\u00fcck. Die Schiedsrichter lie\u00dfen zun\u00e4chst auch weiterspielen um dann doch nach Landsberger Protesten auf Tor zu entscheiden.<\/p>\n<p>Erz\u00fcrnt ob der klaren Fehlentscheidung ging auch die zweite Torwartkelle von EHC-Goalie Carsten Aurich zu Bruch. Nachdem bereits vorher seine erste Kelle abgebrochen war musste er anschlie\u00dfend lange 18 Minuten mit einem Spielerschl\u00e4ger weiterspielen \u2013 was ihn offensichtlich nicht aus der Ruhe brachte.<\/p>\n<p>Wiederum nur 10 Sekunden nach dem Ausgleich brachte Ludwig Danzer seine Mannschaft mit einem unwiderstehlichen Alleingang wieder in Front und kurz vor Ende der Partie besiegelte Michael Reiter in \u00dcberzahl mit seinem dritten Treffer an diesem Tag den hart erk\u00e4mpften 6:4 Sieg.<\/p>\n<p>Am n\u00e4chsten Wochenende sind die EHC Sch\u00fcler zweimal im Einsatz: Am 08.10. gibt der bisher verlustpunktfreie Spitzenreiter SC Riessersee seine Visitenkarte in Grafing ab, am 09.10 steht dann das Ausw\u00e4rtspiel beim Tabellenzweiten EV Lindau an.<\/p>\n<p>HC Landsberg \u2013 EHC Klostersee 4:6 (1:4, 1:0, 2:2)<\/p>\n<p>EHC Klostersee: 1 Carsten Aurich; 3 Noah T\u00f6lg, 4 Benjamin Ibrahimovic, 5 Stefan W\u00fcrmseer (A), 6 Jonathan Mendl, 7 Peter Lechner, 8 Ole Hoffmann, 11 Ludwig Danzer (C), 15 Charlotte Sumpf (A), 16 Tobias Langenbein, 18 Maximilian Jannasch, 19 Patrick Rintermann, 21 Arnaud Eibl, 23 Bernhard Pleithner, 24 Michael Reiter<\/p>\n<p>Tore: 0:1 (1:28) Reiter (Langenbein, W\u00fcrmseer); 1:1 (6:42); 1:2 (7:49) Hoffmann (Danzer); 1:3 (7:58) Reiter; 1:4 (8:23) W\u00fcrmseer (Reiter); 2:4 (20:35); 3:4 (41:23); 4:4 (42:03); 4:5 (42:13) Danzer; 4:6 (57:33) Reiter (Langenbein)<br \/>\nStrafminuten: HC Landsberg 6; EHC Klostersee 12<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sch\u00fclerteam weiter erfolgreich \u2013 EHC gewinnt 6:4 in Landsberg.\u00a0 Nach dem erfolgreichen Auftaktwochende wartete am Sonntagnachmittag mit dem HC Landsberg die n\u00e4chste Ausw\u00e4rtsh\u00fcrde auf die EHC-Sch\u00fcler. Wie bereits im ersten Spiel gegen Pei\u00dfenberg kamen die EHCler hellwach aus der Kabine und legten bereits in der 2. Minute vor: 1:0 durch Michael Reiter nach sch\u00f6ner Kombination [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/853"}],"collection":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/comments?post=853"}],"version-history":[{"count":3,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/853\/revisions"}],"predecessor-version":[{"id":873,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/853\/revisions\/873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media\/856"}],"wp:attachment":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media?parent=853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/categories?post=853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/tags?post=853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}