{"id":2801,"date":"2018-12-30T15:36:32","date_gmt":"2018-12-30T14:36:32","guid":{"rendered":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/?p=2801"},"modified":"2019-01-25T16:08:58","modified_gmt":"2019-01-25T15:08:58","slug":"30-12-2018-ehc-klostersee-hc-landsberg-37-13-10-14","status":"publish","type":"post","link":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/2018\/12\/30\/30-12-2018-ehc-klostersee-hc-landsberg-37-13-10-14\/","title":{"rendered":"30.12.2018 EHC Klostersee &#8211; HC Landsberg 3:7 (1:3; 1:0; 1:4)"},"content":{"rendered":"<p style=\"margin: 0cm;margin-bottom: .0001pt\"><span style=\"font-size: 10.0pt;font-family: 'Arial',sans-serif;color: black\">Nach dem erfolgreichen Kraftakt in Erding empfing die U17 des EHC Klostersee den aktuellen Tabellenf\u00fchrer, HC Landsberg. Gleich auf f\u00fcnf Spieler mussten die Gastgeber (Krankheit, Aushilfe U20 oder gesperrt) verzichten. Den Schwung aus den letzten beiden Siegen konnte die Mannschaft trotzdem mitnehmen und ging mit dem ersten Torabschluss in der 1. Spielminute durch Arnaud Eibl (Maximilian Jannasch) mit 1:0 in F\u00fchrung. Aufopferungsvoll k\u00e4mpfend und stets gef\u00e4hrlich in Kontersituationen konnten die Rot-Wei\u00dfen den hohen Favoriten Paroli bieten. In der 17. Minute war allerdings der Bann gebrochen und die starke Torfrau Paula Weber das erste Mal bezwungen, 1:1. Bereits 30 Sekunden sp\u00e4ter zappelte der Puck zum 1:2 f\u00fcr die G\u00e4ste im Grafinger Geh\u00e4use. Als auch noch das 1:3 in der 18. Minute fiel, schien die Gegenwehr der Hausherren gebrochen. Der Pausentee hatte wohl geholfen. Wieder ein Blitzstart der EHC&#8217;ler und es stand nur noch 2:3. Torsch\u00fctze war Felix Lohmeier. Befl\u00fcgelt durch den Anschlusstreffer erspielten sich die Rot-Wei\u00dfen nun eine Chance nach der\u00a0Anderen. Zu\u00a0diesem Zeitpunkt war man dem Klassenprimus sogar \u00fcberlegen und h\u00e4tte bei konsequenter Chancenverwertung mindestens mit 5:3 f\u00fchren m\u00fcssen. Stattdessen ging es mit\u00a0einem\u00a02:3 R\u00fcckstand in die zweite Drittelpause. Im Schlussabschnitt kannten die Hausherren wieder nur eine Richtung. Vollgas auf&#8217;s Landsberger Tor. Aber diese Drangphase konnten die G\u00e4ste schadlos \u00fcberstehen und sich selbst immer mehr befreien. Folge daraus war in der 46. Minute das 2:4. Postwendend konnte zwar Maximilian Jannasch noch das 3:4 erzielen, aber damit war das Pulver verschossen und die letzten K\u00f6rner aufgebraucht. Dem Vortagessieg Tribut zollend, schwanden immer mehr die Kr\u00e4fte. So\u00a0konnten die Landsberger\u00a0in den folgenden Minuten das Ergebnis noch auf 3:7 stellen und die Punkte mit nach Hause nehmen. Auch wenn dieses\u00a0Spiel verloren ging. Hut ab vor der Moral und vor allem der k\u00e4mpferischen Einstellung der Mannschaft.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0cm;margin-bottom: .0001pt\"><span style=\"font-size: 10.0pt;font-family: 'Arial',sans-serif;color: black\">Es spielten:<\/span><\/p>\n<p style=\"margin: 0cm;margin-bottom: .0001pt\"><span style=\"font-size: 10.0pt;font-family: 'Arial',sans-serif;color: black\">Paula Weber (TW) 33 Min, Marcel K\u00e4smaier (TW) 27 Min.;\u00a0 Noah T\u00f6lg, Bernhard Sch\u00f6nig, Leander Ru\u00df,\u00a0Andrei Zinchenko, Tobias Hilger,\u00a0Raphael Siehr, Charlotte Sumpf, Leopold Weinzierl,\u00a0Rene Mertz, Maximilian Jannasch (1 Tor\/1 Assist), Arnaud Eibl (1\/0), Felix Lohmeier (1\/0),\u00a0Bernhard Pleithner\u00a0\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"foogallery foogallery-container foogallery-default foogallery-lightbox-foobox fg-gutter-10 fg-center fg-default fg-light fg-border-thin fg-shadow-outline fg-loading-default fg-loaded-fade-in fg-caption-hover fg-hover-fade fg-hover-zoom fg-ready\" id=\"foogallery-gallery-2806\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true,&quot;src&quot;:&quot;data-src-fg&quot;,&quot;srcset&quot;:&quot;data-srcset-fg&quot;}\" data-fg-common-fields=\"1\" >\r\n\t<div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0849.jpg\" data-attachment-id=\"2807\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0849\/2669877873.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0856-1.jpg\" data-attachment-id=\"2808\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0856-1\/827436820.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0866.jpg\" data-attachment-id=\"2809\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0866\/1360931155.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0872.jpg\" data-attachment-id=\"2810\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0872\/2176418370.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0874.jpg\" data-attachment-id=\"2811\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0874\/3385943327.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0881.jpg\" data-attachment-id=\"2812\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0881\/401707397.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0902.jpg\" data-attachment-id=\"2813\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0902\/1130607002.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0905.jpg\" data-attachment-id=\"2814\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0905\/1431518215.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0911.jpg\" data-attachment-id=\"2815\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0911\/1214629988.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0913.jpg\" data-attachment-id=\"2816\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0913\/1127873078.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0914.jpg\" data-attachment-id=\"2817\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0914\/3355123189.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0927.jpg\" data-attachment-id=\"2818\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0927\/3340091649.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0941.jpg\" data-attachment-id=\"2819\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0941\/4234633174.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/2018\/12\/DSC_0942.jpg\" data-attachment-id=\"2820\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img width=\"80\" height=\"80\" data-src-fg=\"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-content\/uploads\/sites\/6\/cache\/2018\/12\/DSC_0942\/4235104725.jpg\" class=\"fg-image\" \/><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Nach dem erfolgreichen Kraftakt in Erding empfing die U17 des EHC Klostersee den aktuellen Tabellenf\u00fchrer, HC Landsberg. Gleich auf f\u00fcnf Spieler mussten die Gastgeber (Krankheit, Aushilfe U20 oder gesperrt) verzichten. Den Schwung aus den letzten beiden Siegen konnte die Mannschaft trotzdem mitnehmen und ging mit dem ersten Torabschluss in der 1. Spielminute durch Arnaud Eibl [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2809,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2801"}],"collection":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/comments?post=2801"}],"version-history":[{"count":4,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2801\/revisions"}],"predecessor-version":[{"id":2909,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2801\/revisions\/2909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media\/2809"}],"wp:attachment":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media?parent=2801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/categories?post=2801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/tags?post=2801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}