{"id":2723,"date":"2018-12-12T17:36:46","date_gmt":"2018-12-12T16:36:46","guid":{"rendered":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/?p=2723"},"modified":"2018-12-12T17:41:29","modified_gmt":"2018-12-12T16:41:29","slug":"07-12-2018-deggendorfer-sc-ehc-klostersee-95-32-51-12","status":"publish","type":"post","link":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/2018\/12\/12\/07-12-2018-deggendorfer-sc-ehc-klostersee-95-32-51-12\/","title":{"rendered":"07.12.2018 Deggendorfer SC \u2013 EHC Klostersee 9:5  (3:2; 5:1; 1:2)"},"content":{"rendered":"<p>Am Wochenende stand f\u00fcr die Jugend-Mannschaft des EHC Klostersees ein Doppelspielwochenende an. Bereits am Freitag ging es zum Gastspiel nach Deggendorf. Im dritten Spiel gegen die Deggendorfer wollte die Rot-Wei\u00dfen nun endlich Ihren Negativlauf stoppen und endlich den ersten Sieg einfahren. Auch ohne die beiden Leistungstr\u00e4ger Stefan W\u00fcrmseer und Bernhard Pleithner begannen die EHC\u2019ler forsch und erspielten sich sofort die ersten Torchancen. In der 2. Minute nutzte ein davon Arnaud Eibl nach sch\u00f6ner Kombination mit Felix Lohmeier. Was danach folgte, ist ein Spiegelbild der letzten Wochen. Vorne die eigenen klaren Torchancen nicht genutzt, hinten die Tore per Konter gefangen. Damit konnten die Gastgeber die Partie zum 3-1 drehen. Hoffnung keimte nochmals im Grafinger Lager auf, als Leander Ru\u00df drei Sekunden vor Drittelende auf 3-2 verk\u00fcrzen konnte. \u00a0Die Freude w\u00e4hrte aber nur kurz. In der 23. Minute erh\u00f6hte der DSC auf 4-2 und mit dem 5-2 in der 28. Minute war die Moral und Gegenwehr der Grafinger gebrochen. Wieder und wieder lie\u00df die Mannschaft nun ein Scheibenschie\u00dfen auf die bemitleidenswerten Grafinger Schlussleute\u00a0 zu. Beide machten trotz der daraus resultierenden 9-5 Klatsche einen guten Job.<\/p>\n<p>Es Spielten:<\/p>\n<p>Maximilian Stinauer (TW) 40. Min, Paula Weber (TW) 20. Min.; Noah T\u00f6lg, Bernhard Sch\u00f6nig, Maximilian B\u00f6hm, Korbinian Tristl (0\/1), Tommy, M\u00fcller, Leander Ru\u00df (1 Tor\/1 Assist), Tobias Hilger, Raphael Siehr, Charlotte Sumpf, Leopold Weinzierl, Maximilian Jannasch (1\/0), Patrick Rintermann, Anraud Eibl (1\/0), Felix Lohmeier (1\/2), Nicolas Lechner, Julius Sumpf (1\/0)<\/p>\n<p>Strafen: Deggendorfer SC\u00a0\u00a0 18 Min., EHC Klostersee 8 Min. + 10 Min. Disz. + 20 Min. Spieldauer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Wochenende stand f\u00fcr die Jugend-Mannschaft des EHC Klostersees ein Doppelspielwochenende an. Bereits am Freitag ging es zum Gastspiel nach Deggendorf. Im dritten Spiel gegen die Deggendorfer wollte die Rot-Wei\u00dfen nun endlich Ihren Negativlauf stoppen und endlich den ersten Sieg einfahren. Auch ohne die beiden Leistungstr\u00e4ger Stefan W\u00fcrmseer und Bernhard Pleithner begannen die EHC\u2019ler forsch [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2723"}],"collection":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/comments?post=2723"}],"version-history":[{"count":1,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2723\/revisions"}],"predecessor-version":[{"id":2724,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2723\/revisions\/2724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media\/2561"}],"wp:attachment":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media?parent=2723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/categories?post=2723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/tags?post=2723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}