{"id":2346,"date":"2018-10-08T19:13:36","date_gmt":"2018-10-08T17:13:36","guid":{"rendered":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/?p=2346"},"modified":"2018-10-08T22:41:39","modified_gmt":"2018-10-08T20:41:39","slug":"06-10-2018-tsv-erding-ehc-klostersee-104-13-51-40","status":"publish","type":"post","link":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/2018\/10\/08\/06-10-2018-tsv-erding-ehc-klostersee-104-13-51-40\/","title":{"rendered":"06.10.2018 TSV Erding &#8211; EHC Klostersee 10:4 (1:3; 5:1; 4:0)"},"content":{"rendered":"<p>Am 3. Spieltag war die Jugendmannschaft beim TSV Erding zu Gast. Wohl mit den Gedanken noch in der Kabine, erwischten die Rot-Wei\u00dfen einen denkbar schlechten Start und lagen bereits nach einer Minute mit 1-0 im R\u00fcckstand. Der Treffer muss unsere Jungs aufgeweckt haben. Was sie dann im 1. Drittel ablieferten, war mit Abstand das Beste, was die Mannschaft in der noch jungen Saison (inkl. Vorbereitungsspiele) gezeigt hat. Spielwitz, Spritzigkeit, Torabschl\u00fcsse \u2026 , alles war dabei. Folgerichtig gingen sie mit einer 3-1 F\u00fchrung in die erste Drittelpause. Die Treffer erzielten Felix Lohmeier, Stefan W\u00fcrmseer sowie Maximilian Jannasch. Die Treffer 2 und 3 wurden \u00fcberragend von Arnaud Eibl vorbereitet. Dieser zeichnete sich dann auch gleich im 2. Abschnitt f\u00fcr das 4-1 aus, als er zuerst noch einen Gegenspieler ins Leere rutschen und dann den Heimgoalie keine Chance lie\u00df. Selbst die Erdinger Zuschauer rechneten nun mit einer deutlichen Klatsche f\u00fcr ihre Mannschaft. Warum anschlie\u00dfend die EHC\u2019ler jeglichen Spielbetrieb einstellten, bleibt das Geheimnis der Mannschaft. Noch im Mitteldrittel konnten die Erdinger das Ergebnis drehen und auf 6-4 davon ziehen. Die Treffer zum 5 und 6 zu 4 fielen sogar in eigener doppelter \u00dcberzahl. Damit war an diesem Abend die Moral gebrochen. Die Erdinger machten es mit dem 10:4 am Ende sogar noch gn\u00e4dig. Wichtige Erkenntnis aus diesem Spiel bleibt, dass nur mit 100%igem Einsatz und Willen in dieser Liga zu bestehen ist.<\/p>\n<p>Es spielten:<\/p>\n<p>Maximilian Stinauer (TW), Marcel K\u00e4smaier (TW); Noah T\u00f6lg (0Tor \/ 0 Assist), Bernhard Sch\u00f6nig, Stefan W\u00fcrmseer (1\/2), Korbinian Tristl, Leander Ru\u00df, Tobias Hilger (0\/1), Charlotte Sumpf, Leopold Weinzierl, Maximilian Jannasch (1\/0),\u00a0 Arnaud Eibl (1\/2), Felix Lohmaier (1\/0), Bernhard Pleithner<\/p>\n<p>Strafen:\u00a0 TSV Erding\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 16 min<\/p>\n<p>EHC Klostersee 20 min + 10 min + 10 min<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 3. Spieltag war die Jugendmannschaft beim TSV Erding zu Gast. Wohl mit den Gedanken noch in der Kabine, erwischten die Rot-Wei\u00dfen einen denkbar schlechten Start und lagen bereits nach einer Minute mit 1-0 im R\u00fcckstand. Der Treffer muss unsere Jungs aufgeweckt haben. Was sie dann im 1. Drittel ablieferten, war mit Abstand das Beste, [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2346"}],"collection":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/comments?post=2346"}],"version-history":[{"count":3,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2346\/revisions"}],"predecessor-version":[{"id":2402,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/posts\/2346\/revisions\/2402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media\/2357"}],"wp:attachment":[{"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/media?parent=2346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/categories?post=2346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nachwuchs.ehc-klostersee.de\/u17\/wp-json\/wp\/v2\/tags?post=2346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}